{"id":312,"date":"2011-08-04T00:47:23","date_gmt":"2011-08-03T23:47:23","guid":{"rendered":"http:\/\/www.wandel-verlag.de\/?p=312"},"modified":"2020-02-13T19:44:23","modified_gmt":"2020-02-13T18:44:23","slug":"martin-boord","status":"publish","type":"post","link":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/","title":{"rendered":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)"},"content":{"rendered":"<p><a href=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-442 alignleft\" title=\"Martin Boord\" src=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" srcset=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048-224x300.jpg 224w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048-112x150.jpg 112w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048-767x1024.jpg 767w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048-125x166.jpg 125w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/048.jpg 1015w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a>Als einer von Chhimed Rigdzin Rinpoches \u00e4lteren Sch\u00fclern wird Martin Boord bereits vielen innerhalb der Khordong-Sangha bekannt sein. Nachdem er den Lama w\u00e4hrend einer Pilgerreise durch Indien im Jahre 1973 traf, lud Martin einige Jahre sp\u00e4ter C. R. Lama nach Gro\u00dfbritannien ein, um die \u00dcbertragung des Byangter Phurpa (Vajrakila des N\u00f6rdlichen Schatzes) in Europa zu beginnen. Martin hat viele Belehrungen von Rinpoche erhalten, doch den Schwerpunkt bildeten die Vajrakila- und Sch\u00fctzerbelehrungen. Dreimal bekam er Belehrungen zu Vajrakila und \u00fcbersetzte einen langen Praxistext. Das Thema des Byangter Phurpa nahm er mit zur Universit\u00e4t und absolvierte dort den Bachelor of Arts (BA) in &#8220;Religious Studies (Buddhism)&#8221;. \u00dcber die Gottheit Vajrakila promovierte er zum Dr. phil. an der &#8220;School of oriental and african study&#8221; der Londoner Universit\u00e4t (&#8220;The Cult of the Deity Vajrakila&#8221;, Tring, 1993, \u00fcberarbeitet und erg\u00e4nzt erh\u00e4ltlich als <a title=\"Gathering the Elements von Rig-\u2019dzin rdo-rje (Martin J Boord)\" href=\"https:\/\/www.wandel-verlag.de\/gathering-the-elements\/\">Gathering the Elements<\/a>, Wandel Verlag, 2013).<\/p>\n<p>Als Martin Boord 1967 das erste mal dem tibetischen Buddhismus im Katmandutal begegnete, war er sehr beeindruckt von der Gro\u00dfartigkeit und Sch\u00f6nheit des Tantrayana und des tibetischen Buddhismus. Er begann mit seinem formellen Unterricht in Dharamsala an der Tibetischen Bibliothek, indem er den Sutrapfad f\u00fcr 2 Jahre studierte, obwohl er bereits an den Belehrungen von Padmasambhava interessiert war. Dabei traf er seinen ersten Lehrer, Lama Khandrul Yeshe Dorje, bekannt als der &#8220;Regenmacher&#8221;, ein Nyingma Lama. Martin lebte mit ihm als sein Gehilfe und Adjutant f\u00fcr einige Jahre und blieb f\u00fcr insgesamt 8 Jahre in Indien, haupts\u00e4chlich an tibetischen Orten mit Tibetanern. Er studierte ebenso Sanskrit um das Dharma in seiner urspr\u00fcnglichen Form kennenzulernen.<\/p>\n<p>Ein weiterer wichtiger Lehrer von dem Martin wichtige Belehrungen erhielt war S.H. Dudjom Rinpoche, das Oberhaupt der Nyingma Schule des tibetischen Buddhismus.<\/p>\n<p><a href=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1424 alignright\" src=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut-233x300.jpg\" alt=\"\" width=\"233\" height=\"300\" srcset=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut-233x300.jpg 233w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut-117x150.jpg 117w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut-125x161.jpg 125w, https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg 528w\" sizes=\"auto, (max-width: 233px) 100vw, 233px\" \/><\/a>Martin traf S.H. Chhimed Rigdzin zum ersten mal, als er 1973 mit Lama Khandrul Yeshe Dorje auf Pilgerreise in Sarnath war. Zur\u00fcck in England lie\u00df er sich 1974 in Cornwall nieder und gr\u00fcndete mit seiner Frau ein kleines Dharmazentrum und lud 1979\/80 Chhimed Rigdzin Rinpoche zu seinem ersten Besuch nach England ein. Daraufhin folgte Martin Rinpoche nach Indien zur Universit\u00e4t in Shantiniketan, bekannt durch Rabindrad Tagore, wo Martin sich dem \u00dcbersetzerteam um Rinpoche f\u00fcr einige Zeit anschlo\u00df.<\/p>\n<p>Wieder zur\u00fcck in England und nach einem lockeren Drei-Jahres-Retreat in Schottland fuhr er an der Universit\u00e4t von London mit seinem Studium des Buddhismus fort und zog nach dem PHD (Doktorgrad) nach Oxford um.<\/p>\n<p>Martin Boord lebte lange Oxford und widmet sich vor allem der \u00dcbersetzung tantrischer Texte zur Visualisationsgottheit Vajrakila. Seine erste Ver\u00f6ffenltichung, die bei edition khordong erschien, ist seine mehrere Jahre dauernden \u00dcbersetzung des Phur &#8216;grel &#8216;bum nag, die Schwarzen 100.000 Worte, einem Text der Kamatradition.<\/p>\n<p>Es handelt sich dabei um einen Bericht von einem Vajrakila Retreat, das Padmasambhava mit Vimalamitra und Shilamanju in Nepal im 8. Jahrhundert abgehalten haben. Dieser Bericht wurde von Padmasambhava an die Yogini Yeshe Tsogyal gegeben. Er ist der bekannteste und meist respektierte Kommentar zu Vajrakila. Dieser Text ist nun zur englischsprachigen Ver\u00f6ffentlichung erh\u00e4ltlich. Weitere Informationen zum Buch: &#8220;<a title=\"A Bolt Of Lightning From The Blue von Martin Boord (Rig-\u2019dzin rdo-rje)\" href=\"https:\/\/www.wandel-verlag.de\/a-bolt-of-lightning-from-the-blue\/\">A BOLT OF LIGHTNING FROM THE BLUE<\/a>&#8220;.<\/p>\n<p>Martin Boord kam das erste mal im Jahre 1998 zu Belehrungen \u00fcber Vajrakila nach Deutschland. Dort im Pfauenhof Retreat machte er uns mit der Geschichte und der Meditationspraxis von Vajrakila vertraut. 1999 begleitete er auf \u00e4hnliche Weise ein Vajrakila Retreat mit S.H. Chhimed Rigdzin Rinpoche in Berlin und erg\u00e4nzte es durch seine genauen Erl\u00e4uterungen. Nun wird Martin Boord in einigen L\u00e4ndern Europas regelm\u00e4\u00dfig zu Belehrungen des Vajrayana eingeladen, so auch nach \u00d6sterreich und Schweden und begleitete Rinpoche auf einigen Stationen in Europa.<\/p>\n<p><strong>Bibliographie<\/strong><\/p>\n<p>&#8211; &#8220;The Cult of the Deity Vajrakila&#8221;, Tring, 1993 (vergriffen, \u00fcberarbeitete und erweiterte Neuauflage im April 2013 als Volume One der <em>Vajrakila texts of the Northern Treasures Tradition: <a title=\"Gathering the Elements von Rig-\u2019dzin rdo-rje (Martin J Boord)\" href=\"https:\/\/www.wandel-verlag.de\/gathering-the-elements-von-rig-%e2%80%99dzin-rdo-rje-martin-j-boord\/\">Gathering the Elements. The Cult of the Wrathful Deity Vajrakila<\/a><\/em>)<\/p>\n<p>&#8211; &#8220;<a title=\"A Bolt Of Lightning From The Blue von Martin Boord (Rig-\u2019dzin rdo-rje)\" href=\"https:\/\/www.wandel-verlag.de\/a-bolt-of-lightning-from-the-blue\/\">A BOLT OF LIGHTNING FROM THE BLUE. The vast commentary on Vajrakila<br \/>\nthat hits the essential point.<\/a>&#8221; einschl. Padmasambhava&#8217;s Kommentar <em>Phur &#8216;grel &#8216;bum nag, <\/em>edition khordong, berlin, 2002<\/p>\n<p>&#8211; &#8220;<a title=\"A Roll Of Thunder From The Void von Martin Boord (Rig-\u2019dzin rdo-rje)\" href=\"https:\/\/www.wandel-verlag.de\/roll-of-thunder\/\">A Roll Of Thunder From The Void. Vajrakila texts of the Northern Treasures Tradition. Volume Two.<\/a>&#8221; Vajrak\u012bla Texts of the Northern Treasures Tradition, volume two. einschl. des Byangter Phurba Textes, edition khordong im Wandel Verlag, berlin, 2010<\/p>\n<p>&#8211; &#8220;<a title=\"Illuminating Sunshine: Buddhist funeral rituals of Avalokite\u015bvara by Martin Boord (Rig-\u2019dzin rdo-rje)\" href=\"https:\/\/www.wandel-verlag.de\/illuminating-sunshine\/\">Illuminating Sunshine: Buddhist funeral rituals of Avalokite\u015bvara<\/a>&#8221; edition khordong im Wandel Verlag, berlin, 2012<\/p>\n<p>&#8211; &#8220;<a href=\"https:\/\/www.wandel-verlag.de\/a-blaze-of-fire-in-the-dark\/\">A Blaze of Fire in the Dark<\/a>&#8221; Homa rituals for the fulfilment of vows and the performance of deeds of great benefit. Vajrak\u012bla Texts of the Northern Treasures Tradition, volume three. edition khordong im Wandel Verlag, berlin, 2015<\/p>\n<p>&#8211; div. \u00dcbersetzungen von Sadhanas der Khordong Tradition zusammen mit S.H. Chhimed Rigdzin Rinpoche, einschl. der Byangter Phurba Praxis Texte<\/p>\n<p>&#8211; &#8220;Das illustrierte Tibetische Totenbuch&#8221;, kommentierte Neuausgabe, kommentiert von Stephen Hodge und Martin Boord, 144 S., \u00fcbersetzt von Martin Rometsch, Urania Verlag, 2000; orig.: &#8220;The Illustrated Tibetan Book Of The Death&#8221;, Stephen Hodge and Martin Boord, Thorsons, an imprint of HarperCollinsPublishers, Hammersmith, London, 1999<\/p>\n<p>&#8211; sowie weitere englischsprachige Ver\u00f6ffentlichungen und Zusammenarbeiten. Siehe f\u00fcr eine vollst\u00e4ndigere Bibliografie die <a title=\"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)\" href=\"https:\/\/www.wandel-verlag.de\/martin-boord\/\">englischsprachige Biografie<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martin Boord gilt als der westliche Experte f\u00fcr die Vajrakila Praxis, insbesondere f\u00fcr den Byangter Phurba und die N\u00f6rdlichen Sch\u00e4tze im Allgemeinen. Er ist Sch\u00fcler von  Lama Khandrul Yeshe Dorje, Dudjom Rinpoche und Chhimed Rigdzin Rinpoche und studierte mit diesen in Indien. An der Universit\u00e4t von London erhielt er seinen Doktortitel mit seiner Arbeit &#8220;The Cult of the Deity Vajrakila&#8221; und unterrichtete f\u00fcr einige Jahre an der Universit\u00e4t in Oxford. Er widmet sein Leben den Studien der N\u00f6rdlichen Sch\u00e4tze von Rigdzim Godem und im speziellen der Vajrakila Praxis. <a href=\"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":1424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autor"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin\" \/>\n<meta property=\"og:description\" content=\"Martin Boord gilt als der westliche Experte f\u00fcr die Vajrakila Praxis, insbesondere f\u00fcr den Byangter Phurba und die N\u00f6rdlichen Sch\u00e4tze im Allgemeinen. Er ist Sch\u00fcler von Lama Khandrul Yeshe Dorje, Dudjom Rinpoche und Chhimed Rigdzin Rinpoche und studierte mit diesen in Indien. An der Universit\u00e4t von London erhielt er seinen Doktortitel mit seiner Arbeit &quot;The Cult of the Deity Vajrakila&quot; und unterrichtete f\u00fcr einige Jahre an der Universit\u00e4t in Oxford. Er widmet sein Leben den Studien der N\u00f6rdlichen Sch\u00e4tze von Rigdzim Godem und im speziellen der Vajrakila Praxis. Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/\" \/>\n<meta property=\"og:site_name\" content=\"WANDEL VERLAG berlin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wandel.verlag\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-03T23:47:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-13T18:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"528\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webmaster\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"webmaster\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/\"},\"author\":{\"name\":\"webmaster\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/person\\\/e61d13c05314ae9ce364c5d202bddf4c\"},\"headline\":\"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)\",\"datePublished\":\"2011-08-03T23:47:23+00:00\",\"dateModified\":\"2020-02-13T18:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/\"},\"wordCount\":843,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/Martin-La-bearb-web-cut.jpg\",\"articleSection\":[\"Autoren\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/\",\"name\":\"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/Martin-La-bearb-web-cut.jpg\",\"datePublished\":\"2011-08-03T23:47:23+00:00\",\"dateModified\":\"2020-02-13T18:44:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/Martin-La-bearb-web-cut.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/Martin-La-bearb-web-cut.jpg\",\"width\":528,\"height\":679},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/martin-boord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\",\"name\":\"WANDEL VERLAG berlin\",\"description\":\"edition khordong\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#organization\",\"name\":\"edition khordong im Wandel Verlag\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/wandelkhordong_logo_150x225-e1604923349635.gif\",\"contentUrl\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/wandelkhordong_logo_150x225-e1604923349635.gif\",\"width\":100,\"height\":150,\"caption\":\"edition khordong im Wandel Verlag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wandel.verlag\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/person\\\/e61d13c05314ae9ce364c5d202bddf4c\",\"name\":\"webmaster\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g\",\"caption\":\"webmaster\"},\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/author\\\/tsultrim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/","og_locale":"en_US","og_type":"article","og_title":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin","og_description":"Martin Boord gilt als der westliche Experte f\u00fcr die Vajrakila Praxis, insbesondere f\u00fcr den Byangter Phurba und die N\u00f6rdlichen Sch\u00e4tze im Allgemeinen. Er ist Sch\u00fcler von Lama Khandrul Yeshe Dorje, Dudjom Rinpoche und Chhimed Rigdzin Rinpoche und studierte mit diesen in Indien. An der Universit\u00e4t von London erhielt er seinen Doktortitel mit seiner Arbeit \"The Cult of the Deity Vajrakila\" und unterrichtete f\u00fcr einige Jahre an der Universit\u00e4t in Oxford. Er widmet sein Leben den Studien der N\u00f6rdlichen Sch\u00e4tze von Rigdzim Godem und im speziellen der Vajrakila Praxis. Continue reading &rarr;","og_url":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/","og_site_name":"WANDEL VERLAG berlin","article_publisher":"https:\/\/www.facebook.com\/wandel.verlag","article_published_time":"2011-08-03T23:47:23+00:00","article_modified_time":"2020-02-13T18:44:23+00:00","og_image":[{"width":528,"height":679,"url":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg","type":"image\/jpeg"}],"author":"webmaster","twitter_card":"summary_large_image","twitter_misc":{"Written by":"webmaster","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#article","isPartOf":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/"},"author":{"name":"webmaster","@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/person\/e61d13c05314ae9ce364c5d202bddf4c"},"headline":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)","datePublished":"2011-08-03T23:47:23+00:00","dateModified":"2020-02-13T18:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/"},"wordCount":843,"publisher":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#organization"},"image":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg","articleSection":["Autoren"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/","url":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/","name":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje) - WANDEL VERLAG berlin","isPartOf":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#primaryimage"},"image":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg","datePublished":"2011-08-03T23:47:23+00:00","dateModified":"2020-02-13T18:44:23+00:00","breadcrumb":{"@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wandel-verlag.de\/de\/martin-boord\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#primaryimage","url":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg","contentUrl":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/Martin-La-bearb-web-cut.jpg","width":528,"height":679},{"@type":"BreadcrumbList","@id":"https:\/\/www.wandel-verlag.de\/de\/martin-boord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wandel-verlag.de\/en\/"},{"@type":"ListItem","position":2,"name":"Dr. Martin J. Boord (Rig-\u2019dzin rdo-rje)"}]},{"@type":"WebSite","@id":"https:\/\/www.wandel-verlag.de\/en\/#website","url":"https:\/\/www.wandel-verlag.de\/en\/","name":"WANDEL VERLAG berlin","description":"edition khordong","publisher":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wandel-verlag.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.wandel-verlag.de\/en\/#organization","name":"edition khordong im Wandel Verlag","url":"https:\/\/www.wandel-verlag.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/wandelkhordong_logo_150x225-e1604923349635.gif","contentUrl":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/wandelkhordong_logo_150x225-e1604923349635.gif","width":100,"height":150,"caption":"edition khordong im Wandel Verlag"},"image":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wandel.verlag"]},{"@type":"Person","@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/person\/e61d13c05314ae9ce364c5d202bddf4c","name":"webmaster","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b181a83ef1f3d1f6d66b9695ae355d97042db8e0d8b1927b0e9ef0b7bb3e568?s=96&d=mm&r=g","caption":"webmaster"},"url":"https:\/\/www.wandel-verlag.de\/de\/author\/tsultrim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/posts\/312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/comments?post=312"}],"version-history":[{"count":0,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/posts\/312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/media\/1424"}],"wp:attachment":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/media?parent=312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/categories?post=312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/tags?post=312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}