{"id":41,"count":1,"description":"","link":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/","name":"Puja","slug":"puja","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puja Archive - WANDEL VERLAG berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puja Archive - WANDEL VERLAG berlin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/\" \/>\n<meta property=\"og:site_name\" content=\"WANDEL VERLAG berlin\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/kordong-logo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1708\" \/>\n\t<meta property=\"og:image:height\" content=\"1729\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/tag\\\/puja\\\/\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/tag\\\/puja\\\/\",\"name\":\"Puja Archive - WANDEL VERLAG berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/tag\\\/puja\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/de\\\/tag\\\/puja\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puja\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\",\"name\":\"WANDEL VERLAG berlin\",\"description\":\"edition khordong\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#organization\",\"name\":\"edition khordong im Wandel Verlag\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/wandelkhordong_logo_150x225-e1604923349635.gif\",\"contentUrl\":\"https:\\\/\\\/www.wandel-verlag.de\\\/wp-content\\\/uploads\\\/wandelkhordong_logo_150x225-e1604923349635.gif\",\"width\":100,\"height\":150,\"caption\":\"edition khordong im Wandel Verlag\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wandel-verlag.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wandel.verlag\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puja Archive - WANDEL VERLAG berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/","og_locale":"en_US","og_type":"article","og_title":"Puja Archive - WANDEL VERLAG berlin","og_url":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/","og_site_name":"WANDEL VERLAG berlin","og_image":[{"width":1708,"height":1729,"url":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/kordong-logo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/","url":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/","name":"Puja Archive - WANDEL VERLAG berlin","isPartOf":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wandel-verlag.de\/de\/tag\/puja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.wandel-verlag.de\/en\/"},{"@type":"ListItem","position":2,"name":"Puja"}]},{"@type":"WebSite","@id":"https:\/\/www.wandel-verlag.de\/en\/#website","url":"https:\/\/www.wandel-verlag.de\/en\/","name":"WANDEL VERLAG berlin","description":"edition khordong","publisher":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wandel-verlag.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.wandel-verlag.de\/en\/#organization","name":"edition khordong im Wandel Verlag","url":"https:\/\/www.wandel-verlag.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/wandelkhordong_logo_150x225-e1604923349635.gif","contentUrl":"https:\/\/www.wandel-verlag.de\/wp-content\/uploads\/wandelkhordong_logo_150x225-e1604923349635.gif","width":100,"height":150,"caption":"edition khordong im Wandel Verlag"},"image":{"@id":"https:\/\/www.wandel-verlag.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wandel.verlag"]}]}},"_links":{"self":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/tags\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.wandel-verlag.de\/de\/wp-json\/wp\/v2\/posts?tags=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}